{"id":3114,"date":"2022-08-10T17:10:41","date_gmt":"2022-08-10T15:10:41","guid":{"rendered":"http:\/\/qualitel.org\/?post_type=projet&#038;p=3114"},"modified":"2026-08-10T14:49:06","modified_gmt":"2026-08-10T12:49:06","slug":"quelles-sont-les-garanties-liees-a-la-vente-dun-logement-en-etat-de-futur-achevement-vefa","status":"publish","type":"projet","link":"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/","title":{"rendered":"Garantie Vefa&#160;: quelles sont les assurances li\u00e9es \u00e0 la vente d\u2019un logement en \u00e9tat futur d&rsquo;ach\u00e8vement&#160;?"},"content":{"rendered":"<p>Depuis 2016, les op\u00e9rations de vente en l\u2019\u00e9tat futur d\u2019ach\u00e8vement (Vefa) <strong>ne peuvent plus faire l\u2019objet d\u2019une garantie intrins\u00e8que<\/strong>, autrement dit bas\u00e9e sur l\u2019\u00e9tat d\u2019avancement des travaux et\/ou de financement du projet immobilier. Le<strong> promoteur<\/strong> est tenu de fournir aux acheteurs une garantie extrins\u00e8que qui prend la forme d\u2019une <strong>garantie financi\u00e8re de l&rsquo;ach\u00e8vement de l&rsquo;immeuble ou d\u2019une garantie financi\u00e8re du remboursement des versements effectu\u00e9s en cas de r\u00e9solution du contrat \u00e0 d\u00e9faut d&rsquo;ach\u00e8vement des travaux<\/strong>.<\/p>\n<p>Aujourd\u2019hui, il existe ainsi deux garanties li\u00e9es \u00e0 la vente en \u00e9tat futur d\u2019ach\u00e8vement (Vefa) afin d\u2019encadrer l\u2019op\u00e9ration immobili\u00e8re et de prot\u00e9ger les particuliers qui souhaitent <a href=\"http:\/\/www.qualitel.org\/particuliers\/acheter-logement\/vefa\/avantages-inconvenients\/\">acheter sur plan<\/a>&#160;: <strong>\u00ab&#160;remboursement&#160;\u00bb<\/strong> et <strong>\u00ab&#160;ach\u00e8vement&#160;\u00bb<\/strong>.<\/p>\n<p>Lors de la signature du <a href=\"https:\/\/www.qualitel.org\/particuliers\/comprendre-vos-documents\/contrat-de-reservation-vefa\/\" target=\"_blank\" rel=\"noopener\">contrat de r\u00e9servation<\/a> (ou avant-contrat), le promoteur vous propose de choisir l\u2019une ou l\u2019autre de ces garanties d&rsquo;achat sur plan. Pour vous permettre de faire le bon choix selon vos attentes, voici des explications sur les caract\u00e9ristiques de ces deux garanties \u00e0 prendre en compte avant d\u2019acheter un bien en vefa.<\/p>\n<h3>La garantie de remboursement<\/h3>\n<p>Aussi connue sous le nom de <strong>garantie extrins\u00e8que de remboursement<\/strong>, elle intervient dans le cas o\u00f9 l\u2019ach\u00e8vement du logement ne peut avoir lieu \u00e0 cause d\u2019une d\u00e9faillance du promoteur immobilier (<a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/article_lc\/LEGIARTI000039041584\" target=\"_blank\" rel=\"noopener\">article R 261-22 du code de la construction et de l\u2019habitation<\/a>). Le contrat de vente est alors caduc. L\u2019acheteur est rembours\u00e9 des sommes d\u00e9j\u00e0 vers\u00e9es par la caution du promoteur (un \u00e9tablissement financier). Cependant, tous les frais li\u00e9s \u00e0 l\u2019achat ne sont pas couverts.<\/p>\n<p>Cette garantie remboursement fonctionne m\u00eame si le promoteur est impliqu\u00e9 dans une <strong>proc\u00e9dure de redressement ou de liquidation judiciaire<\/strong>.<\/p>\n<p>Elle peut \u00e9galement \u00eatre utilis\u00e9e lorsque des <strong>recours sont d\u00e9pos\u00e9s contre les permis de construire<\/strong> du programme immobilier neuf.<\/p>\n<h3>La garantie d\u2019ach\u00e8vement<\/h3>\n<p>Cette garantie VEFA est <strong>activ\u00e9e lors d\u2019une d\u00e9faillance du promoteur<\/strong> et vous assure que votre maison ou appartement sera termin\u00e9 et livr\u00e9. La soci\u00e9t\u00e9 d\u2019assurance ou la banque li\u00e9e au promoteur s\u2019engage \u00e0 financer les travaux n\u00e9cessaires \u00e0 l\u2019ach\u00e8vement, pour vous livrer votre logement.<\/p>\n<p>Ces deux garanties prennent fin \u00e0 l\u2019ach\u00e8vement du logement, qui co\u00efncide g\u00e9n\u00e9ralement avec la remise des cl\u00e9s.<\/p>\n<p>&#160;<\/p>\n<p>La garantie de parfait ach\u00e8vement, obligatoire en cas de vente VEFA, peut <strong>couvrir les d\u00e9sordres li\u00e9s \u00e0 l&rsquo;isolation acoustique<\/strong>. Le premier acqu\u00e9reur peut faire jouer cette garantie pendant un an \u00e0 compter de la prise de possession du bien, lorsque les exigences minimales de la r\u00e9glementation acoustique ne sont pas atteintes (bruits a\u00e9riens int\u00e9rieurs\/ext\u00e9rieurs, bruits de choc, etc.). En cas de d\u00e9fauts d&rsquo;isolation phonique av\u00e9r\u00e9s, le vendeur ou le ma\u00eetre d\u2019ouvrage doit r\u00e9parer les malfa\u00e7ons constat\u00e9es.<\/p>\n<p>Dans le cas particulier des logements neufs vendus en Vefa, un certain nombre de garanties l\u00e9gales existent pour prot\u00e9ger l\u2019acqu\u00e9reur des d\u00e9fauts de conformit\u00e9 (vices apparents, vices cach\u00e9s, malfa\u00e7ons&#8230;) ou du non ach\u00e8vement du programme apr\u00e8s la signature de l\u2019acte de vente d\u00e9finitif. C\u2019est alors la responsabilit\u00e9 des entreprises ayant effectu\u00e9 les travaux qui est invoqu\u00e9e. Mais <a href=\"https:\/\/www.service-public.fr\/particuliers\/vosdroits\/F2958\" target=\"_blank\" rel=\"noopener\">quelles garanties<\/a> faire jouer apr\u00e8s la r\u00e9ception des travaux&#160;?<\/p>\n<h3>La garantie de parfait ach\u00e8vement<\/h3>\n<p>Si vous constatez des d\u00e9sordres au cours de la premi\u00e8re ann\u00e9e apr\u00e8s la livraison des travaux, sachez que vous \u00eates prot\u00e9g\u00e9s par la&#160;<b>garantie de parfait ach\u00e8vement<\/b>.<\/p>\n<p>Ce dispositif <strong>fonctionne pour tous les d\u00e9fauts<\/strong>, quelles que soient leur nature et leur importance. Pour l\u2019activer, vous devez notifier toutes les anomalies par lettre recommand\u00e9e avec accus\u00e9 de r\u00e9ception. Les promoteurs immobiliers, qui sont les ma\u00eetres d\u2019ouvrage au moment de la construction de l\u2019appartement ou de la maison individuelle, devront les faire corriger.<\/p>\n<h3>La garantie biennale ou de bon fonctionnement des \u00e9quipements<\/h3>\n<p><strong>Obligatoire pour les constructions de logement<\/strong>, cette garantie vous permet de faire remplacer ou r\u00e9parer des \u00e9quipements d\u00e9fectueux (<a href=\"https:\/\/www.qualitel.org\/particuliers\/equipements-et-materiaux-maison\/chauffage\/chaudieres\/\">chaudi\u00e8re<\/a>, <a href=\"https:\/\/www.qualitel.org\/particuliers\/equipements-et-materiaux\/robinetterie\/\">robinetterie<\/a>, volets, plaques de cuisson, etc.) hors gros \u0153uvre et ce pendant deux ans \u00e0 compter de la r\u00e9ception de travaux. Pour la d\u00e9clencher, informez le promoteur par lettre recommand\u00e9e avec accus\u00e9 de r\u00e9ception.<\/p>\n<h3>La garantie d\u00e9cennale<\/h3>\n<p>Valable pour toute construction, y compris la Vefa, la <a href=\"https:\/\/www.qualitel.org\/particuliers\/travaux-renovation\/assurance\/garantie-decennale\/\">garantie d\u00e9cennale<\/a> vous couvre pour tous les dommages qui touchent \u00e0 l\u2019\u00e9tanch\u00e9it\u00e9, \u00e0 la solidit\u00e9 de la structure (fissures), \u00e0 la toiture, aux fen\u00eatres\u2026 tout ce que l\u2019on appelle le \u00ab&#160;clos et couvert&#160;\u00bb et qui concerne l&rsquo;\u00ab&#160;habitabilit\u00e9&#160;\u00bb du logement. Elle<strong> court sur dix ans d\u00e8s la livraison<\/strong> du logement et se transmet aux acqu\u00e9reurs successifs, pendant tout le d\u00e9lai de la garantie Vefa.<\/p>\n<p>D\u00e8s que vous constatez un probl\u00e8me dans les 10 ans apr\u00e8s l\u2019ach\u00e8vement de l\u2019immeuble et la r\u00e9ception des travaux, signalez-le au promoteur par lettre recommand\u00e9e avec avis de r\u00e9ception au vendeur.<\/p>\n<h3>L\u2019assurance dommages-ouvrage<\/h3>\n<p>Obligatoire pour le promoteur qui doit la contracter avant le d\u00e9but des travaux de construction, l&rsquo;<a href=\"https:\/\/www.qualitel.org\/particuliers\/travaux-renovation\/assurance\/assurance-dommage-ouvrage\/\">assurance dommages-ouvrage<\/a> vous sera transmise \u00e0 la livraison du logement. Elle <strong>commence \u00e0 courir un an apr\u00e8s la r\u00e9ception des travaux<\/strong> (soit \u00e0 l\u2019expiration de la garantie de parfait ach\u00e8vement) et se termine en m\u00eame temps que la garantie d\u00e9cennale.<\/p>\n<p>Dans les faits, elle vous permet de <strong>b\u00e9n\u00e9ficier d&rsquo;une prise en charge rapide par l\u2019assureur<\/strong> des r\u00e9parations des d\u00e9sordres qui rel\u00e8vent de la garantie d\u00e9cennale. Cela \u00e9vite d\u2019attendre la fin des proc\u00e9dures judiciaires contre les entreprises intervenant sur le chantier du logement et le r\u00e9sultat des expertises pour d\u00e9terminer les responsabilit\u00e9s.<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","categories":[203,208,213,220],"tags":[446,458],"guide":[332],"article_type":[],"class_list":["post-3114","projet","type-projet","status-publish","hentry","category-confort","category-eco-responsabilite","category-sante","category-securite","tags-achat","tags-assurances","guide-guide-transverse-dachat"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quelles sont les 5 garanties de l&#039;achat Vefa&#160;? - Qualitel | Particuliers<\/title>\n<meta name=\"description\" content=\"Quelles garanties sont li\u00e9es \u00e0 un appartement vendu en Vefa&#160;? Nos experts font le point sur les diff\u00e9rentes garanties Vefa&#160;: parfait ach\u00e8vement, biennale, d\u00e9cennale, dommages-ouvrage\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelles sont les garanties li\u00e9es \u00e0 la vente d\u2019un logement en \u00e9tat futur d&#039;ach\u00e8vement (Vefa)&#160;?\" \/>\n<meta property=\"og:description\" content=\"Vous envisagez d&rsquo;acheter un bien immobilier sur plans en Vefa, mais avez des doutes sur les garanties l\u00e9gales en cas de probl\u00e8me&#160;? D\u00e9couvrez quelles assurances vous prot\u00e8gent et comment faire valoir vos droits en cas d&rsquo;anomalies non d\u00e9tect\u00e9es durant le proc\u00e8s-verbal de livraison.\n&#160;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/\" \/>\n<meta property=\"og:site_name\" content=\"Qualitel | Particuliers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groupequalitel\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-10T12:49:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.qualitel.org\/particuliers\/wp\/..\/uploads\/qualitel_social_part.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Quelles sont les garanties li\u00e9es \u00e0 la vente d\u2019un logement en \u00e9tat futur d&#039;ach\u00e8vement (Vefa)&#160;?\" \/>\n<meta name=\"twitter:description\" content=\"Vous envisagez d&rsquo;acheter un bien immobilier sur plans en Vefa, mais avez des doutes sur les garanties l\u00e9gales en cas de probl\u00e8me&#160;? D\u00e9couvrez quelles assurances vous prot\u00e8gent et comment faire valoir vos droits en cas d&rsquo;anomalies non d\u00e9tect\u00e9es durant le proc\u00e8s-verbal de livraison.\n&#160;\n\" \/>\n<meta name=\"twitter:site\" content=\"@groupeQUALITEL\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/\",\"url\":\"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/\",\"name\":\"Quelles sont les 5 garanties de l'achat Vefa ? - Qualitel | Particuliers\",\"isPartOf\":{\"@id\":\"https:\/\/www.qualitel.org\/particuliers\/#website\"},\"datePublished\":\"2022-08-10T15:10:41+00:00\",\"dateModified\":\"2026-08-10T12:49:06+00:00\",\"description\":\"Quelles garanties sont li\u00e9es \u00e0 un appartement vendu en Vefa ? Nos experts font le point sur les diff\u00e9rentes garanties Vefa : parfait ach\u00e8vement, biennale, d\u00e9cennale, dommages-ouvrage\u2026\",\"breadcrumb\":{\"@id\":\"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.qualitel.org\/particuliers\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garantie Vefa&#160;: quelles sont les assurances li\u00e9es \u00e0 la vente d\u2019un logement en \u00e9tat futur d&rsquo;ach\u00e8vement&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.qualitel.org\/particuliers\/#website\",\"url\":\"https:\/\/www.qualitel.org\/particuliers\/\",\"name\":\"Qualitel | Particuliers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.qualitel.org\/particuliers\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.qualitel.org\/particuliers\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.qualitel.org\/particuliers\/#organization\",\"name\":\"Qualitel | Particuliers\",\"url\":\"https:\/\/www.qualitel.org\/particuliers\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.qualitel.org\/particuliers\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.qualitel.org\/particuliers\/wp\/..\/uploads\/qualitel-squarelogo-1456752654225.png\",\"contentUrl\":\"https:\/\/www.qualitel.org\/particuliers\/wp\/..\/uploads\/qualitel-squarelogo-1456752654225.png\",\"width\":180,\"height\":180,\"caption\":\"Qualitel | Particuliers\"},\"image\":{\"@id\":\"https:\/\/www.qualitel.org\/particuliers\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/groupequalitel\/\",\"https:\/\/x.com\/groupeQUALITEL\",\"https:\/\/www.instagram.com\/associationqualitel\/\",\"https:\/\/www.pinterest.fr\/associationqualitel\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quelles sont les 5 garanties de l'achat Vefa&#160;? - Qualitel | Particuliers","description":"Quelles garanties sont li\u00e9es \u00e0 un appartement vendu en Vefa&#160;? Nos experts font le point sur les diff\u00e9rentes garanties Vefa&#160;: parfait ach\u00e8vement, biennale, d\u00e9cennale, dommages-ouvrage\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/","og_locale":"fr_FR","og_type":"article","og_title":"Quelles sont les garanties li\u00e9es \u00e0 la vente d\u2019un logement en \u00e9tat futur d'ach\u00e8vement (Vefa)&#160;?","og_description":"Vous envisagez d&rsquo;acheter un bien immobilier sur plans en Vefa, mais avez des doutes sur les garanties l\u00e9gales en cas de probl\u00e8me&#160;? D\u00e9couvrez quelles assurances vous prot\u00e8gent et comment faire valoir vos droits en cas d&rsquo;anomalies non d\u00e9tect\u00e9es durant le proc\u00e8s-verbal de livraison.\n&#160;","og_url":"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/","og_site_name":"Qualitel | Particuliers","article_publisher":"https:\/\/www.facebook.com\/groupequalitel\/","article_modified_time":"2026-08-10T12:49:06+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.qualitel.org\/particuliers\/wp\/..\/uploads\/qualitel_social_part.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Quelles sont les garanties li\u00e9es \u00e0 la vente d\u2019un logement en \u00e9tat futur d'ach\u00e8vement (Vefa)&#160;?","twitter_description":"Vous envisagez d&rsquo;acheter un bien immobilier sur plans en Vefa, mais avez des doutes sur les garanties l\u00e9gales en cas de probl\u00e8me&#160;? D\u00e9couvrez quelles assurances vous prot\u00e8gent et comment faire valoir vos droits en cas d&rsquo;anomalies non d\u00e9tect\u00e9es durant le proc\u00e8s-verbal de livraison.\n&#160;\n","twitter_site":"@groupeQUALITEL","twitter_misc":{"Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/","url":"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/","name":"Quelles sont les 5 garanties de l'achat Vefa ? - Qualitel | Particuliers","isPartOf":{"@id":"https:\/\/www.qualitel.org\/particuliers\/#website"},"datePublished":"2022-08-10T15:10:41+00:00","dateModified":"2026-08-10T12:49:06+00:00","description":"Quelles garanties sont li\u00e9es \u00e0 un appartement vendu en Vefa ? Nos experts font le point sur les diff\u00e9rentes garanties Vefa : parfait ach\u00e8vement, biennale, d\u00e9cennale, dommages-ouvrage\u2026","breadcrumb":{"@id":"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.qualitel.org\/particuliers\/acheter-logement\/garanties-vefa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.qualitel.org\/particuliers\/"},{"@type":"ListItem","position":2,"name":"Garantie Vefa&#160;: quelles sont les assurances li\u00e9es \u00e0 la vente d\u2019un logement en \u00e9tat futur d&rsquo;ach\u00e8vement&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/www.qualitel.org\/particuliers\/#website","url":"https:\/\/www.qualitel.org\/particuliers\/","name":"Qualitel | Particuliers","description":"","publisher":{"@id":"https:\/\/www.qualitel.org\/particuliers\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.qualitel.org\/particuliers\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.qualitel.org\/particuliers\/#organization","name":"Qualitel | Particuliers","url":"https:\/\/www.qualitel.org\/particuliers\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.qualitel.org\/particuliers\/#\/schema\/logo\/image\/","url":"https:\/\/www.qualitel.org\/particuliers\/wp\/..\/uploads\/qualitel-squarelogo-1456752654225.png","contentUrl":"https:\/\/www.qualitel.org\/particuliers\/wp\/..\/uploads\/qualitel-squarelogo-1456752654225.png","width":180,"height":180,"caption":"Qualitel | Particuliers"},"image":{"@id":"https:\/\/www.qualitel.org\/particuliers\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groupequalitel\/","https:\/\/x.com\/groupeQUALITEL","https:\/\/www.instagram.com\/associationqualitel\/","https:\/\/www.pinterest.fr\/associationqualitel\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.qualitel.org\/particuliers\/wp-json\/wp\/v2\/projet\/3114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.qualitel.org\/particuliers\/wp-json\/wp\/v2\/projet"}],"about":[{"href":"https:\/\/www.qualitel.org\/particuliers\/wp-json\/wp\/v2\/types\/projet"}],"version-history":[{"count":120,"href":"https:\/\/www.qualitel.org\/particuliers\/wp-json\/wp\/v2\/projet\/3114\/revisions"}],"predecessor-version":[{"id":54326,"href":"https:\/\/www.qualitel.org\/particuliers\/wp-json\/wp\/v2\/projet\/3114\/revisions\/54326"}],"wp:attachment":[{"href":"https:\/\/www.qualitel.org\/particuliers\/wp-json\/wp\/v2\/media?parent=3114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.qualitel.org\/particuliers\/wp-json\/wp\/v2\/categories?post=3114"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.qualitel.org\/particuliers\/wp-json\/wp\/v2\/tags?post=3114"},{"taxonomy":"guide","embeddable":true,"href":"https:\/\/www.qualitel.org\/particuliers\/wp-json\/wp\/v2\/guide?post=3114"},{"taxonomy":"projet_type","embeddable":true,"href":"https:\/\/www.qualitel.org\/particuliers\/wp-json\/wp\/v2\/article_type?post=3114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}